{"id":2513,"date":"2022-08-08T12:09:17","date_gmt":"2022-08-08T09:09:17","guid":{"rendered":"http:\/\/foreverclinica.com\/dhi-sac-ekimi\/"},"modified":"2024-07-24T11:42:30","modified_gmt":"2024-07-24T08:42:30","slug":"trapianto-di-capelli-dhi","status":"publish","type":"page","link":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/","title":{"rendered":"Trapianto di Capelli DHI"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2513\" class=\"elementor elementor-2513 elementor-659\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a031cf0 elementor-section-full_width dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"a031cf0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf43b72 dsvy-bg-color-over-image\" data-id=\"bf43b72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87fe453 fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"87fe453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n                            <div class=\"fluentform-widget-heading\">\n                                        <div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#modulo-di-appuntamento-online\" >Modulo di appuntamento online<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#procedura-di-trapianto-di-capelli-dhi\" >Procedura di trapianto di capelli DHI<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#come-viene-eseguito-il-trapianto-di-capelli-dhi\" >Come viene eseguito il trapianto di capelli Dhi?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#quanto-tempo-richiede-il-trapianto-di-capelli-dhi\" >Quanto tempo richiede il trapianto di capelli Dhi?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#quali-sono-i-vantaggi-del-trapianto-di-capelli-dhi\" >Quali sono i vantaggi del trapianto di capelli Dhi?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#processo-di-trapianto-di-capelli-post-dhi\" >Processo di trapianto di capelli post-Dhi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#quanti-giorni-impiega-il-trapianto-di-capelli-dhi-per-guarire\" >Quanti giorni impiega il trapianto di capelli Dhi per guarire?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#prezzi-del-trapianto-di-capelli-dhi\" >Prezzi del trapianto di capelli Dhi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#le-nostre-referenze-per-il-trapianto-di-capelli\" >Le nostre referenze per il trapianto di capelli<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#contattaci\" >Contattaci<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#il-nostro-numero-di-telefono\" >Il nostro numero di telefono<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#il-nostro-indirizzo\" >Il nostro indirizzo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#il-nostro-indirizzo-e-mail\" >Il nostro indirizzo e-mail<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#crea-un-appuntamento-gratuito\" >Crea un appuntamento gratuito<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3 class=\"fluentform-widget-title\"><span class=\"ez-toc-section\" id=\"modulo-di-appuntamento-online\"><\/span>\n                        Modulo di appuntamento online                    <span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                        <\/div>\n            \n            <div class='fluentform ff-default fluentform_wrapper_16 ffs_default_wrap'><form data-form_id=\"16\" id=\"fluentform_16\" class=\"frm-fluent-form fluent_form_16 ff-el-form-top ff_form_instance_16_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_16_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">italyanca \u0130leti\u015fim Formu yatay (#4) (#16)<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2513' \/><input type=\"hidden\" id=\"_fluentform_16_fluentformnonce\" name=\"_fluentform_16_fluentformnonce\" value=\"cd0fc5d11a\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/2513\" \/><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_5 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 20%;'><div class='ff-el-group'><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_16_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_16_dropdown\"><option value=\"\">Operazioni<\/option><option value=\"Trapianto di capelli\"  >Trapianto di capelli<\/option><option value=\"Rinoplastica (Estetica del Naso)\"  >Rinoplastica (Estetica del Naso)<\/option><option value=\"Estetica del seno\"  >Estetica del seno<\/option><option value=\"Trattamenti dentistici\"  >Trattamenti dentistici<\/option><option value=\"Liposuzione (rimozione del grasso)\"  >Liposuzione (rimozione del grasso)<\/option><option value=\"BBL (sollevamento dei glutei brasiliano)\"  >BBL (sollevamento dei glutei brasiliano)<\/option><option value=\"Fecondazione in vitro (IVF)\"  >Fecondazione in vitro (IVF)<\/option><option value=\"Obesit\u00e0\"  >Obesit\u00e0<\/option><option value=\"Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)\"  >Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)<\/option><option value=\"Altro\"  >Altro<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 20%;'><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group'><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_16_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Nome cognome\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-3' style='flex-basis: 20%;'><div class='ff-el-group'><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_16_email\" class=\"ff-el-form-control\" placeholder=\"E-mail\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-4' style='flex-basis: 20%;'><div class='ff-el-group'><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Numero di telefono\" data-name=\"input_text\" id=\"ff_16_input_text\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-5' style='flex-basis: 20%;'><div class='ff-el-group ff-text-center ff_submit_btn_wrapper ff_submit_btn_wrapper_custom'><button class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style wpf_has_custom_css\" type=\"submit\" name=\"custom_submit_button-16_1\" data-name=\"custom_submit_button-16_1\"  aria-label=\"Inviare\">Inviare<\/button><style>form.fluent_form_16 .wpf_has_custom_css.ff-btn-submit { background-color:#409EFF;border-color:#409EFF;color:#ffffff;min-width:100%; }form.fluent_form_16 .wpf_has_custom_css.ff-btn-submit:hover { background-color:#ffffff;border-color:#409EFF;color:#409EFF;min-width:100%; } <\/style><\/div><\/div><\/div><\/fieldset><\/form><div id='fluentform_16_errors' class='ff-errors-in-stack ff_form_instance_16_1 ff-form-loading_errors ff_form_instance_16_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_16_1 = {\"id\":\"16\",\"ajaxUrl\":\"https:\\\/\\\/foreverclinica.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"id\":\"39\",\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_16_1\",\"form_id_selector\":\"fluentform_16\",\"rules\":{\"dropdown\":{\"required\":{\"value\":true,\"message\":\"Bu alan gereklidir\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"Please enter a valid email address.\",\"global\":false,\"global_message\":\"This field must contain a valid email\"}},\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e084afd dsvy-bg-color-yes dsvy-elementor-bg-color-white elementor-section-content-middle dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e084afd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d897e1 dsvy-bg-color-over-image\" data-id=\"8d897e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b566240 dsvy-align-left elementor-widget elementor-widget-dsvy_heading\" data-id=\"b566240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"dsvy-heading-subheading -align dsvy-reverse-heading-yes\"><h4 class=\"dsvy-element-subtitle\">\r\n\t\t\t\r\n\t\t\t\tForever Clinica\r\n\t\t\t\r\n\t\t\t<\/h4>\r\n\t\t<h2 class=\"dsvy-element-title\"><span class=\"ez-toc-section\" id=\"procedura-di-trapianto-di-capelli-dhi\"><\/span>\r\n\t\t\t\r\n\t\t\t\tProcedura di trapianto di capelli DHI\r\n\t\t\t\r\n\t\t\t<span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d6ad3f elementor-widget elementor-widget-text-editor\" data-id=\"0d6ad3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><\/p>\n<table id=\"tablepress-98\" class=\"tablepress tablepress-id-98\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Servizio<\/td><td class=\"column-2\">America<\/td><td class=\"column-3\">Germania<\/td><td class=\"column-4\">Regno Unito<\/td><td class=\"column-5\">Spagna<\/td><td class=\"column-6\">Francia<\/td><td class=\"column-7\">Italia<\/td><td class=\"column-8\">Turchia (Forever Clinica)<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Trapianto di Capelli DHI<\/td><td class=\"column-2\">$6.000<\/td><td class=\"column-3\">\u20ac3.500<\/td><td class=\"column-4\">\u00a33.000<\/td><td class=\"column-5\">\u20ac3.000<\/td><td class=\"column-6\">\u20ac4.000<\/td><td class=\"column-7\">\u20ac4.000<\/td><td class=\"column-8\">\u20ac1.700<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-98 from cache --><p>Sebbene la caduta dei capelli possa verificarsi a causa di fattori ambientali secondari come la cura e l\u2019alimentazione, pu\u00f2 anche verificarsi frequentemente a causa di vari problemi di salute come tigna e irregolarit\u00e0 ormonali. L\u2019ormone testosterone negli uomini ha molti effetti sui follicoli piliferi e, in questo caso, la diminuzione dell\u2019ormone testosterone dovuta all\u2019invecchiamento provoca un aumento della caduta dei capelli.<\/p><p>L\u2019unico modo per prevenire la perdita permanente dei capelli chiamata \u201ccalvizie\u201d sviluppando vari metodi di trattamento per risolvere questo problema, che pu\u00f2 colpire persone di quasi tutte le et\u00e0, \u00e8 attraverso il trapianto di capelli.<\/p><p>Da quando \u00e8 stato eseguito il primo trapianto di capelli nel 1939, sono state provate molte applicazioni diverse e sono stati sviluppati standard applicativi. Pertanto, \u00e8 diventato possibile il trattamento a lungo termine della caduta permanente dei capelli.<\/p><p>Se applicato correttamente da medici esperti nel campo dell\u2019estrazione di unit\u00e0 follicolari (FUE) e dell\u2019impianto diretto di capelli, che sono sviluppati e ampiamente utilizzati con la tecnologia odierna, si ottengono risultati visibili ed eccellenti.<\/p><p><a title=\"trapianto di capelli dhi\" href=\"http:\/\/foreverclinica.com\/dhi-sac-ekimi\/\"><strong>trapianto di capelli dhi<\/strong>&lt;\/a, che \u00e8 piuttosto importante tra i capelli metodi di trapianto &gt;\u00c8 diventato uno dei metodi di trapianto di capelli pi\u00f9 preferiti negli ultimi anni.<\/a><\/p><p>Tra i metodi di trapianto di capelli, il trapianto di capelli con il metodo dhi viene eseguito da una penna medica chiamata choi. Questa penna consente di procedere direttamente alla fase del trapianto di capelli dopo la raccolta del follicolo pilifero.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-11876 size-full\" src=\"http:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_2259427019.jpg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_2259427019.jpg 1000w, https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_2259427019-300x169.jpg 300w, https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_2259427019-768x432.jpg 768w, https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_2259427019-770x434.jpg 770w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p><h2><span class=\"ez-toc-section\" id=\"come-viene-eseguito-il-trapianto-di-capelli-dhi\"><\/span>Come viene eseguito il trapianto di capelli Dhi?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Il metodo dhi di trapianto di capelli, noto come impianto diretto di capelli, \u00e8 definito come uno dei metodi pi\u00f9 importanti in quanto pu\u00f2 essere completato in una singola sessione e il processo di recupero \u00e8 breve.<\/p><p>Con questo metodo, che mira ad ispessire e coprire le zone glabre senza danneggiare le radici sane della pelle e soprattutto i capelli, viene eseguito un trapianto di capelli molto denso e una procedura dall\u2019aspetto naturale. Informazioni dettagliate vengono fornite dai medici alle persone che vengono per il trapianto di capelli in risposta alle domande &#8220;Che cos&#8217;\u00e8 il trapianto di capelli dhi prima della procedura?&#8221;.<\/p><p>I follicoli piliferi vengono esaminati in dettaglio con un dispositivo che fornisce immagini ad alta risoluzione e vengono determinate tutte le caratteristiche della salute dei capelli della persona, il tipo di capelli, la densit\u00e0 attuale dei capelli e la gravit\u00e0 della caduta. Successivamente viene progettato il trapianto di capelli pi\u00f9 adatto alla persona e la prima procedura inizia immediatamente dopo l\u2019applicazione dell\u2019anestesia locale.<\/p><p>Nel metodo di trapianto di capelli dhi, vengono generalmente preferiti e utilizzati i follicoli piliferi prelevati dalla nuca della persona. Il dispositivo micromotore, uno dei dispositivi tecnologici pi\u00f9 avanzati, aiuta a rimuovere i follicoli piliferi sani dalla nuca. I follicoli piliferi estratti da quest\u2019area vengono posti in una soluzione speciale per proteggere la salute di ciascun follicolo pilifero.<\/p><p>Una volta completata l\u2019estrazione dei follicoli piliferi dalla radice del collo del donatore, viene applicata l\u2019anestesia locale all\u2019area in cui verr\u00e0 eseguito il trapianto di capelli e inizia il processo di trapianto.<\/p><p>Poco prima di iniziare il DHI, \u00e8 necessario analizzare molto bene il progetto del trapianto di capelli da eseguire sulla persona. Pertanto, vengono determinate le direzioni in cui cresceranno i nuovi follicoli piliferi e la progettazione del trapianto di capelli viene eseguita di conseguenza.<\/p><p>Nel metodo DHI, dove non \u00e8 necessario aprire un canale verso l\u2019area calva prima del trapianto di capelli, il numero di sessioni \u00e8 basso e il danno tissutale che appare come una ferita dopo la procedura non \u00e8 incluso. In questo modo \u00e8 inevitabile che coloro che hanno paura degli interventi chirurgici si abituino facilmente a questo metodo di trattamento.<\/p><h3><span class=\"ez-toc-section\" id=\"quanto-tempo-richiede-il-trapianto-di-capelli-dhi\"><\/span>Quanto tempo richiede il trapianto di capelli Dhi?<span class=\"ez-toc-section-end\"><\/span><\/h3><p>L&#8217;operazione di <strong>trapianto di capelli Dhi pro<\/strong> pu\u00f2 variare in termini di durata della procedura a seconda del numero di follicoli piliferi da trapiantare. Questo cambiamento avviene in media tra le 10 e le 12 ore. \u00c8 opportuno tenere in considerazione che alcuni processi potrebbero richiedere pi\u00f9 tempo a causa dell&#8217;utilizzo di pi\u00f9 di una tecnica.<\/p><p>Grazie ai risultati del trapianto di capelli dhi, che \u00e8 uno dei metodi che presenta vantaggi sotto molti aspetti, \u00e8 possibile ottenere capelli dall\u2019aspetto naturale, forti e sani ed eliminare completamente il problema della caduta dei capelli.<\/p><h2><span class=\"ez-toc-section\" id=\"quali-sono-i-vantaggi-del-trapianto-di-capelli-dhi\"><\/span>Quali sono i vantaggi del trapianto di capelli Dhi?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>I vantaggi del trapianto di capelli dhi dichiarati dagli esperti, oltre ad essere permanente per tutta la vita, sono i seguenti;<\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\">Dopo l&#8217;operazione potrete tornare alla vita quotidiana con un recupero assolutamente rapido.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">L&#8217;anestesia locale \u00e8 preferibile all&#8217;anestesia generale.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Dopo l&#8217;operazione non si avverte alcun dolore a lungo termine.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Il rischio di sanguinamento \u00e8 ridotto al minimo poich\u00e9 l&#8217;area dell&#8217;incisione pu\u00f2 essere pi\u00f9 piccola.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">La scanalatura non viene applicata a nessuna parte dei capelli.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Il tasso di sopravvivenza dei follicoli piliferi \u00e8 piuttosto alto.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Con questa tecnica, il trapianto di capelli senza rasatura \u00e8 pi\u00f9 semplice.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Il metodo di trapianto DHI \u00e8 completamente privo di rischi.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Poich\u00e9 i follicoli piliferi vengono trapiantati uno accanto all&#8217;altro, hai capelli spessi e vibranti.<\/li><\/ul><p>Il metodo di trapianto di capelli DHI, i cui vantaggi sono permanenti per tutta la vita, \u00e8 una delle tecniche di trapianto di capelli che probabilmente render\u00e0 le persone estremamente felici. Poich\u00e9 le procedure di trapianto di capelli DHI sono minimamente invasive, \u00e8 estremamente importante che l\u2019applicazione venga eseguita in un ambiente sterile e da un medico.<\/p><p>Dopo le procedure di trapianto di capelli eseguite in un ambiente idoneo e non sterile, si verificano infezioni nel follicolo pilifero e possono causare gravi complicazioni che influiscono sia sui capelli che sulla salute del paziente. Pertanto, la clinica e l\u2019ambiente in cui verr\u00e0 eseguito il trapianto di capelli dovrebbero essere studiati approfonditamente. L&#8217;assenza di buchi, incisioni e punti di sutura sar\u00e0 un processo pi\u00f9 rilassante per coloro che hanno paura di queste procedure.<\/p><h2><span class=\"ez-toc-section\" id=\"processo-di-trapianto-di-capelli-post-dhi\"><\/span>Processo di trapianto di capelli post-Dhi<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Pi\u00f9 i pazienti vengono informati sul periodo di recupero dal trapianto di capelli, pi\u00f9 velocemente progredir\u00e0 il processo di recupero.<\/p><p>Il processo dopo il trapianto di capelli procede come segue;<\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\">Le istruzioni di lavaggio determinate dal medico devono essere seguite scrupolosamente per 10 giorni dopo il trapianto.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Dovrebbero essere utilizzati i derivati \u200b\u200bdel berretto, della sciarpa e del cappello raccomandati dal medico<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Poich\u00e9 le prime settimane sono i periodi pi\u00f9 critici, durante questo periodo \u00e8 opportuno evitare possibili contatti fisici eccessivi con la zona dei capelli.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Quando si asciugano i capelli, non esercitare pressione sui capelli e sulla pelle con un asciugamano<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Il corpo dovrebbe riposare molto e nessun cuscino dovrebbe essere posizionato sulle aree trapiantate durante il sonno.<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Quando si avverte dolore, dovrebbero essere assunti solo gli antidolorifici ritenuti appropriati dal medico<\/li><li style=\"font-weight: 400;\" aria-level=\"1\">Se si devono applicare trattamenti con siero e crema sui capelli, \u00e8 necessario ottenere l&#8217;approvazione del medico.<\/li><\/ul><p>\u00c8 possibile avere un processo indolore e senza problemi purch\u00e9 vengano seguiti i passaggi da seguire dopo il processo di trapianto di capelli dhi. Generalmente il processo di guarigione non richiede molto tempo, anche se varia da persona a persona.<\/p><p>Mentre le foto &#8220;prima e dopo&#8221; del trapianto di capelli scattate dal medico hanno un grande effetto sulle persone, anche lo stato dei capelli di persone che si sono viste senza capelli per molto tempo pu\u00f2 sembrare loro diverso per un po&#8217;. Sebbene il processo di guarigione sia completamente completato entro due settimane, non bisogna dimenticare che possono verificarsi dolore e bruciore al follicolo pilifero.<\/p><h2><span class=\"ez-toc-section\" id=\"quanti-giorni-impiega-il-trapianto-di-capelli-dhi-per-guarire\"><\/span>Quanti giorni impiega il trapianto di capelli Dhi per guarire?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Generalmente, il processo successivo al trapianto di capelli Dhi si traduce in un recupero molto rapido. Sebbene subito dopo l\u2019operazione si verifichino cambiamenti come croste, caduta, dolore e fastidio, alla fine del processo i nuovi capelli iniziano ad apparire immediatamente.<\/p><p>Immediatamente dopo il trapianto di capelli, il paziente pu\u00f2 tornare alla sua vecchia vita e al lavoro quotidiano. Ascoltare le raccomandazioni del medico aiuta i follicoli piliferi a guarire bene e i capelli della persona ritornano alla normalit\u00e0 il prima possibile.<\/p><p>L&#8217;aspetto dei capelli che il paziente sogna \u00e8 possibile solo se applicato correttamente e creando una combinazione solida seguendo le semplici istruzioni del medico. Sebbene sia necessario in media un anno affinch\u00e9 i nuovi capelli crescano completamente, spetta all\u2019individuo tornare alla vita quotidiana e migliorare le attivit\u00e0 quotidiane dopo il trapianto di capelli.<\/p><p><img decoding=\"async\" class=\"alignnone wp-image-11868 size-full\" src=\"http:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_1994711516.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_1994711516.jpg 1000w, https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_1994711516-300x200.jpg 300w, https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_1994711516-768x512.jpg 768w, https:\/\/foreverclinica.com\/wp-content\/uploads\/2024\/07\/shutterstock_1994711516-770x514.jpg 770w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p><h2><span class=\"ez-toc-section\" id=\"prezzi-del-trapianto-di-capelli-dhi\"><\/span>Prezzi del trapianto di capelli Dhi<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Il paziente deve essere esaminato in dettaglio dal medico per questi prezzi di trapianto di capelli, che variano completamente da persona a persona. Anche la dimensione dell\u2019area in cui verr\u00e0 eseguita la procedura e il numero di innesti da eseguire nel trapianto di capelli sono fattori importanti che influenzano i prezzi. Dopo che l\u2019area in cui verr\u00e0 eseguito il trapianto di capelli viene valutata in clinica, alla persona vengono fornite informazioni sui prezzi e vengono offerte le opzioni.<\/p><p>A seguito degli screening dettagliati eseguiti dal clinico, vengono valutate le opzioni che possono essere adatte alle persone che si sottopongono all&#8217;esame in linea con le reciproche discussioni e richieste.<\/p><p>Questa applicazione di trapianto di capelli, che rientra tra le applicazioni estetiche, rientra anche tra le operazioni in cui i prezzi cambiano con l\u2019uso di strumenti tecnologici e le applicazioni hanno un impatto sui prezzi.<\/p><p>Mentre i pazienti ritenuti idonei ai trattamenti in sessione sono soggetti a un prezzo per sessione, le tariffe determinate per un&#8217;area pi\u00f9 limitata in una singola sessione sono inferiori rispetto ad altre opzioni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f588a18 elementor-widget elementor-widget-progress\" data-id=\"f588a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-title\" id=\"elementor-progress-bar-f588a18\">\n\t\t\t\tFelicit\u00e0 del cliente\t\t\t<\/span>\n\t\t\n\t\t<div aria-labelledby=\"elementor-progress-bar-f588a18\" class=\"elementor-progress-wrapper\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"100\" aria-valuetext=\"100% (Web Designer)\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"100\">\n\t\t\t\t<span class=\"elementor-progress-text\">Web Designer<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-progress-percentage\">100%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f680847 elementor-widget elementor-widget-progress\" data-id=\"f680847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-title\" id=\"elementor-progress-bar-f680847\">\n\t\t\t\tCliente felice\t\t\t<\/span>\n\t\t\n\t\t<div aria-labelledby=\"elementor-progress-bar-f680847\" class=\"elementor-progress-wrapper\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"100\" aria-valuetext=\"100% (Mutlu M\u00fc\u015fteri)\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"100\">\n\t\t\t\t<span class=\"elementor-progress-text\">Mutlu M\u00fc\u015fteri<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-progress-percentage\">100%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-431c9da elementor-section-stretched dsvy-fid-sep dsvy-bg-color-yes dsvy-elementor-bg-color-blackish dsvy-bg-image-over-color dsvy-col-stretched-none elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"431c9da\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e3676b4 dsvy-bg-color-over-image\" data-id=\"e3676b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39dd413 elementor-widget elementor-widget-dsvy_fid_element\" data-id=\"39dd413\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_fid_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"designervily-ele designervily-ele-fid designervily-ele-fid-style-3 \"><div class=\"dsvy-fld-contents\">\r\n\t<div class=\"dsvy-sbox-icon-wrapper\"><i class=\"dsvy-cardioly-icon dsvy-cardioly-icon-heartbeat\"><\/i><\/div>\t<h4 class=\"dsvy-fid-inner\">\r\n\t\t\t\t<span class=\"dsvy-number-rotate\" data-appear-animation=\"animateDigits\" data-from=\"0\" data-to=\"9000\" data-interval=\"5\" data-before=\"\" data-before-style=\"\" data-after=\"\" data-after-style=\"\">\r\n\t\t\t\t9000\t\t<\/span><span class=\"dsvy-fid-sub\"><sup>+<\/sup><\/span>\r\n\t<\/h4>\r\n\t<span class=\"dsvy-fid-title\">Transazione totale<\/span>\r\n<\/div><!-- .dsvy-fld-contents -->\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-98201c8 dsvy-bg-color-over-image\" data-id=\"98201c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b97693 elementor-widget elementor-widget-dsvy_fid_element\" data-id=\"3b97693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_fid_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"designervily-ele designervily-ele-fid designervily-ele-fid-style-3 \"><div class=\"dsvy-fld-contents\">\r\n\t<div class=\"dsvy-sbox-icon-wrapper\"><i class=\"fas fa-users\"><\/i><\/div>\t<h4 class=\"dsvy-fid-inner\">\r\n\t\t\t\t<span class=\"dsvy-number-rotate\" data-appear-animation=\"animateDigits\" data-from=\"0\" data-to=\"4000\" data-interval=\"5\" data-before=\"\" data-before-style=\"\" data-after=\"\" data-after-style=\"\">\r\n\t\t\t\t4000\t\t<\/span><span class=\"dsvy-fid-sub\"><sup>+<\/sup><\/span>\r\n\t<\/h4>\r\n\t<span class=\"dsvy-fid-title\">Numero di pazienti<\/span>\r\n<\/div><!-- .dsvy-fld-contents -->\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6908af9 dsvy-bg-color-over-image\" data-id=\"6908af9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07e328a elementor-widget elementor-widget-dsvy_fid_element\" data-id=\"07e328a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_fid_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"designervily-ele designervily-ele-fid designervily-ele-fid-style-3 \"><div class=\"dsvy-fld-contents\">\r\n\t<div class=\"dsvy-sbox-icon-wrapper\"><i class=\"dsvy-cardioly-icon dsvy-cardioly-icon-phone-call\"><\/i><\/div>\t<h4 class=\"dsvy-fid-inner\">\r\n\t\t\t\t<span class=\"dsvy-number-rotate\" data-appear-animation=\"animateDigits\" data-from=\"0\" data-to=\"20000\" data-interval=\"5\" data-before=\"\" data-before-style=\"\" data-after=\"\" data-after-style=\"\">\r\n\t\t\t\t20000\t\t<\/span><span class=\"dsvy-fid-sub\"><sup>+<\/sup><\/span>\r\n\t<\/h4>\r\n\t<span class=\"dsvy-fid-title\">Telefonata<\/span>\r\n<\/div><!-- .dsvy-fld-contents -->\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e2de4b1 dsvy-bg-color-over-image\" data-id=\"e2de4b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dd4215 elementor-widget elementor-widget-dsvy_fid_element\" data-id=\"4dd4215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_fid_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"designervily-ele designervily-ele-fid designervily-ele-fid-style-3 \"><div class=\"dsvy-fld-contents\">\r\n\t<div class=\"dsvy-sbox-icon-wrapper\"><i class=\"far fa-smile-beam\"><\/i><\/div>\t<h4 class=\"dsvy-fid-inner\">\r\n\t\t\t\t<span class=\"dsvy-number-rotate\" data-appear-animation=\"animateDigits\" data-from=\"0\" data-to=\"100\" data-interval=\"5\" data-before=\"\" data-before-style=\"\" data-after=\"\" data-after-style=\"\">\r\n\t\t\t\t100\t\t<\/span><span class=\"dsvy-fid-sub\"><sup>%<\/sup><\/span>\r\n\t<\/h4>\r\n\t<span class=\"dsvy-fid-title\">Felicit\u00e0 del cliente<\/span>\r\n<\/div><!-- .dsvy-fld-contents -->\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14d3ce7 dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14d3ce7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcef7e5 dsvy-bg-color-over-image\" data-id=\"fcef7e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdef79e dsvy-align-center elementor-widget elementor-widget-dsvy_heading\" data-id=\"bdef79e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"dsvy-heading-subheading -align dsvy-reverse-heading-yes\"><h4 class=\"dsvy-element-subtitle\">\r\n\t\t\t\r\n\t\t\t\tForever Clinica\r\n\t\t\t\r\n\t\t\t<\/h4>\r\n\t\t<h2 class=\"dsvy-element-title\"><span class=\"ez-toc-section\" id=\"le-nostre-referenze-per-il-trapianto-di-capelli\"><\/span>\r\n\t\t\t\r\n\t\t\t\tLe nostre referenze per il trapianto di capelli\r\n\t\t\t\r\n\t\t\t<span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\t\t<div class=\"dsvy-heading-desc\">Puoi vedere i video di soddisfazione e le foto prima e dopo di centinaia di nostri pazienti.<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14237b7 dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14237b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ee28978 dsvy-bg-color-over-image\" data-id=\"ee28978\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b6998e elementor-widget elementor-widget-html\" data-id=\"8b6998e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cf9HxwfKYdf\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Cf9HxwfKYdf\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Cf9HxwfKYdf\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4dabfc5 dsvy-bg-color-over-image\" data-id=\"4dabfc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-806bc08 elementor-widget elementor-widget-html\" data-id=\"806bc08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CgR1F8RoabX\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CgR1F8RoabX\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CgR1F8RoabX\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-260263d dsvy-bg-color-over-image\" data-id=\"260263d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ea39b7 elementor-widget elementor-widget-html\" data-id=\"1ea39b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CgPJUbRozXc\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CgPJUbRozXc\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CgPJUbRozXc\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ed049d dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ed049d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d648555 dsvy-bg-color-over-image\" data-id=\"d648555\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-956a72b elementor-widget elementor-widget-html\" data-id=\"956a72b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cf4FgAiKTeE\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Cf4FgAiKTeE\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Cf4FgAiKTeE\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-72c5d46 dsvy-bg-color-over-image\" data-id=\"72c5d46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79aab33 elementor-widget elementor-widget-html\" data-id=\"79aab33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CgCRWfKKuyf\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CgCRWfKKuyf\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CgCRWfKKuyf\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8b697d0 dsvy-bg-color-over-image\" data-id=\"8b697d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9116bec elementor-widget elementor-widget-html\" data-id=\"9116bec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CfWmaynKKaj\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CfWmaynKKaj\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CfWmaynKKaj\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5934d3e dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5934d3e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a47b696 dsvy-bg-color-over-image\" data-id=\"a47b696\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95b2b0d elementor-widget elementor-widget-html\" data-id=\"95b2b0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CfrGMBJKrBx\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CfrGMBJKrBx\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CfrGMBJKrBx\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c893fdf dsvy-bg-color-over-image\" data-id=\"c893fdf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5396f41 elementor-widget elementor-widget-html\" data-id=\"5396f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Ce0koNUqTaZ\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Ce0koNUqTaZ\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Ce0koNUqTaZ\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5844af8 dsvy-bg-color-over-image\" data-id=\"5844af8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a5aeec elementor-widget elementor-widget-html\" data-id=\"6a5aeec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Ce56vZgK-j6\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Ce56vZgK-j6\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Bu g\u00f6nderiyi Instagram&#39;da g\u00f6r<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Ce56vZgK-j6\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">Forever Clinica (@foreverclinica)&#39;in payla\u015ft\u0131\u011f\u0131 bir g\u00f6nderi<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-862397a dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"862397a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07e6a77 dsvy-bg-color-over-image\" data-id=\"07e6a77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-5a04a3b elementor-section-content-middle dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a04a3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e1a268 dsvy-bg-color-yes dsvy-elementor-bg-color-white dsvy-bg-color-over-image\" data-id=\"1e1a268\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31a632e elementor-widget elementor-widget-heading\" data-id=\"31a632e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"contattaci\"><\/span>Contattaci<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf62f32 elementor-widget elementor-widget-dsvy_icon_heading\" data-id=\"bf62f32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"dsvy-ihbox dsvy-ihbox-style-3\">\r\n<div class=\"dsvy-ihbox-box d-flex\">\r\n\t<div class=\"dsvy-ihbox-icon\"><div class=\"dsvy-ihbox-icon-wrapper\"><i class=\"mdi mdi-local-phone\"><\/i><\/div><\/div>\t<div class=\"dsvy-ihbox-contents\">\r\n\t\t<h2 class=\"dsvy-element-title\"><span class=\"ez-toc-section\" id=\"il-nostro-numero-di-telefono\"><\/span>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\tIl nostro numero di telefono\r\n\t\t\t\t\t\r\n\t\t\t\t\t<span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\t\t\t\t\t\t\t\t<div class=\"dsvy-heading-desc\">+90 544 848 55 85<\/div>\t\t\t<\/div><!-- .dsvy-ihbox-contents -->\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d3dc7 elementor-widget elementor-widget-dsvy_icon_heading\" data-id=\"b3d3dc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"dsvy-ihbox dsvy-ihbox-style-3\">\r\n<div class=\"dsvy-ihbox-box d-flex\">\r\n\t<div class=\"dsvy-ihbox-icon\"><div class=\"dsvy-ihbox-icon-wrapper\"><i class=\"mdi mdi-location-city\"><\/i><\/div><\/div>\t<div class=\"dsvy-ihbox-contents\">\r\n\t\t<h2 class=\"dsvy-element-title\"><span class=\"ez-toc-section\" id=\"il-nostro-indirizzo\"><\/span>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\tIl nostro indirizzo\r\n\t\t\t\t\t\r\n\t\t\t\t\t<span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\t\t\t\t\t\t\t\t<div class=\"dsvy-heading-desc\">\u0130stanbul<br>\nT\u00fcrkiye<\/div>\t\t\t<\/div><!-- .dsvy-ihbox-contents -->\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-939a733 elementor-widget elementor-widget-dsvy_icon_heading\" data-id=\"939a733\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"dsvy_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"dsvy-ihbox dsvy-ihbox-style-3\">\r\n<div class=\"dsvy-ihbox-box d-flex\">\r\n\t<div class=\"dsvy-ihbox-icon\"><div class=\"dsvy-ihbox-icon-wrapper\"><i class=\"mdi mdi-email\"><\/i><\/div><\/div>\t<div class=\"dsvy-ihbox-contents\">\r\n\t\t<h2 class=\"dsvy-element-title\"><span class=\"ez-toc-section\" id=\"il-nostro-indirizzo-e-mail\"><\/span>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\tIl nostro indirizzo e-mail\r\n\t\t\t\t\t\r\n\t\t\t\t\t<span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\t\t\t\t\t\t\t\t<div class=\"dsvy-heading-desc\">info@foreverclinica.com<\/div>\t\t\t<\/div><!-- .dsvy-ihbox-contents -->\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fc5a0d dsvy-contact-social-area elementor-widget elementor-widget-text-editor\" data-id=\"4fc5a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-56417b1 dsvy-bg-color-yes dsvy-elementor-bg-color-blackish dsvy-bg-color-over-image\" data-id=\"56417b1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1466a61 elementor-widget elementor-widget-heading\" data-id=\"1466a61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"ez-toc-section\" id=\"crea-un-appuntamento-gratuito\"><\/span>Crea un appuntamento gratuito<span class=\"ez-toc-section-end\"><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebee995 elementor-widget elementor-widget-text-editor\" data-id=\"ebee995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fatti un favore come migliaia di ospiti di Forever Clinica e fissa subito un appuntamento gratuito.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6866a7 elementor-widget elementor-widget-shortcode\" data-id=\"c6866a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='fluentform ff-default fluentform_wrapper_17 ffs_default_wrap'><form data-form_id=\"17\" id=\"fluentform_17\" class=\"frm-fluent-form fluent_form_17 ff-el-form-top ff_form_instance_17_2 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_17_2\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">italyanca \u0130leti\u015fim Formu (#17)<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='2513' \/><input type=\"hidden\" id=\"_fluentform_17_fluentformnonce\" name=\"_fluentform_17_fluentformnonce\" value=\"cd0fc5d11a\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/2513\" \/><div class='ff-el-group'><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_17_2_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_17_2_dropdown\"><option value=\"\">Seleziona Operazione<\/option><option value=\"Trapianto di capelli\"  >Trapianto di capelli<\/option><option value=\"Rinoplastica (Estetica del Naso)\"  >Rinoplastica (Estetica del Naso)<\/option><option value=\"Estetica del seno\"  >Estetica del seno<\/option><option value=\"Trattamenti dentistici\"  >Trattamenti dentistici<\/option><option value=\"Liposuzione (rimozione del grasso)\"  >Liposuzione (rimozione del grasso)<\/option><option value=\"BBL (sollevamento dei glutei brasiliano)\"  >BBL (sollevamento dei glutei brasiliano)<\/option><option value=\"Fecondazione in vitro (IVF)\"  >Fecondazione in vitro (IVF)<\/option><option value=\"Obezite\"  >Obezite<\/option><option value=\"Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)\"  >Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)<\/option><option value=\"Altro\"  >Altro<\/option><\/select><\/div><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group'><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_17_2_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Nome cognome\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_17_2_email\" class=\"ff-el-form-control\" placeholder=\"E-Mail\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Numero di telefono\" data-name=\"input_text\" id=\"ff_17_2_input_text\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_17_2_message\" name=\"message\" id=\"ff_17_2_message\" class=\"ff-el-form-control\" placeholder=\"Messaggio\" rows=\"4\" cols=\"2\" data-name=\"message\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-right ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style wpf_has_custom_css\"  aria-label=\"Inviare\">Inviare<\/button><\/div><\/fieldset><\/form><div id='fluentform_17_errors' class='ff-errors-in-stack ff_form_instance_17_2 ff-form-loading_errors ff_form_instance_17_2_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_17_2 = {\"id\":\"17\",\"ajaxUrl\":\"https:\\\/\\\/foreverclinica.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"id\":\"39\",\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_17_2\",\"form_id_selector\":\"fluentform_17\",\"rules\":{\"dropdown\":{\"required\":{\"value\":true,\"message\":\"Bu alan gereklidir\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"Please enter a valid email address.\",\"global\":false,\"global_message\":\"This field must contain a valid email\"}},\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"message\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n            <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edfc04e dsvy-col-stretched-none dsvy-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edfc04e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-892a9ee dsvy-bg-color-over-image\" data-id=\"892a9ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2592e2b elementor-widget elementor-widget-html\" data-id=\"2592e2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- TrustBox widget - Review Collector -->\r\n<div class=\"trustpilot-widget\" data-locale=\"en-US\" data-template-id=\"56278e9abfbbba0bdcd568bc\" data-businessunit-id=\"62e69043bce119780b995fc5\" data-style-height=\"52px\" data-style-width=\"100%\">\r\n  <a href=\"https:\/\/www.trustpilot.com\/review\/foreverclinica.com\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a>\r\n<\/div>\r\n<!-- End TrustBox widget -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16) OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Sebbene la caduta dei capelli possa verificarsi a causa di fattori ambientali secondari come la cura e l\u2019alimentazione, pu\u00f2 anche verificarsi frequentemente a causa di vari[&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_joinchat":[],"footnotes":""},"class_list":["post-2513","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Forever Clinica - \u0130stanbul Medikal Estetik Firmas\u0131\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Trapianto di Capelli DHI - Forever Clinica\" \/>\n\t\t<meta property=\"og:description\" content=\"Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-08-08T09:09:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-24T08:42:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Trapianto di Capelli DHI - Forever Clinica\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/trapianto-di-capelli-dhi\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/trapianto-di-capelli-dhi\\\/#listItem\",\"name\":\"Trapianto di Capelli DHI\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/trapianto-di-capelli-dhi\\\/#listItem\",\"position\":2,\"name\":\"Trapianto di Capelli DHI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/#organization\",\"name\":\"Forever Clinica\",\"description\":\"\\u0130stanbul Medikal Estetik Firmas\\u0131\",\"url\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/trapianto-di-capelli-dhi\\\/#webpage\",\"url\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/trapianto-di-capelli-dhi\\\/\",\"name\":\"Trapianto di Capelli DHI - Forever Clinica\",\"description\":\"Modulo di appuntamento online italyanca \\u0130leti\\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/trapianto-di-capelli-dhi\\\/#breadcrumblist\"},\"datePublished\":\"2022-08-08T12:09:17+03:00\",\"dateModified\":\"2024-07-24T11:42:30+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/\",\"name\":\"Forever Clinica\",\"description\":\"\\u0130stanbul Medikal Estetik Firmas\\u0131\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverclinica.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Trapianto di Capelli DHI - Forever Clinica","description":"Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene","canonical_url":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/foreverclinica.com\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/foreverclinica.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#listItem","name":"Trapianto di Capelli DHI"}},{"@type":"ListItem","@id":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#listItem","position":2,"name":"Trapianto di Capelli DHI","previousItem":{"@type":"ListItem","@id":"https:\/\/foreverclinica.com\/it\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/foreverclinica.com\/it\/#organization","name":"Forever Clinica","description":"\u0130stanbul Medikal Estetik Firmas\u0131","url":"https:\/\/foreverclinica.com\/it\/"},{"@type":"WebPage","@id":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#webpage","url":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/","name":"Trapianto di Capelli DHI - Forever Clinica","description":"Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/foreverclinica.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/#breadcrumblist"},"datePublished":"2022-08-08T12:09:17+03:00","dateModified":"2024-07-24T11:42:30+03:00"},{"@type":"WebSite","@id":"https:\/\/foreverclinica.com\/it\/#website","url":"https:\/\/foreverclinica.com\/it\/","name":"Forever Clinica","description":"\u0130stanbul Medikal Estetik Firmas\u0131","inLanguage":"it-IT","publisher":{"@id":"https:\/\/foreverclinica.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Forever Clinica - \u0130stanbul Medikal Estetik Firmas\u0131","og:type":"article","og:title":"Trapianto di Capelli DHI - Forever Clinica","og:description":"Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene","og:url":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/","article:published_time":"2022-08-08T09:09:17+00:00","article:modified_time":"2024-07-24T08:42:30+00:00","twitter:card":"summary_large_image","twitter:title":"Trapianto di Capelli DHI - Forever Clinica","twitter:description":"Modulo di appuntamento online italyanca \u0130leti\u015fim Formu yatay (#4) (#16)OperazioniTrapianto di capelliRinoplastica (Estetica del Naso)Estetica del senoTrattamenti dentisticiLiposuzione (rimozione del grasso)BBL (sollevamento dei glutei brasiliano)Fecondazione in vitro (IVF)Obesit\u00e0Intervento chirurgico di riduzione dello stomaco (manicotto gastrico)AltroInviare Forever Clinica Procedura di trapianto di capelli DHI Contents Toggle Modulo di appuntamento onlineProcedura di trapianto di capelli DHICome viene"},"aioseo_meta_data":{"post_id":"2513","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-11 23:39:41","updated":"2025-06-05 19:57:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/foreverclinica.com\/it\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTrapianto di Capelli DHI\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/foreverclinica.com\/it\/"},{"label":"Trapianto di Capelli DHI","link":"https:\/\/foreverclinica.com\/it\/trapianto-di-capelli-dhi\/"}],"_links":{"self":[{"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/pages\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/comments?post=2513"}],"version-history":[{"count":35,"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/pages\/2513\/revisions"}],"predecessor-version":[{"id":12845,"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/pages\/2513\/revisions\/12845"}],"wp:attachment":[{"href":"https:\/\/foreverclinica.com\/it\/wp-json\/wp\/v2\/media?parent=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}